{"id":54293,"date":"2023-08-22T21:46:42","date_gmt":"2023-08-22T19:46:42","guid":{"rendered":"https:\/\/temporary.mindd.dev\/?p=54293"},"modified":"2024-05-19T16:32:25","modified_gmt":"2024-05-19T14:32:25","slug":"teil-2-in-der-serie-revisionsprozess-leitender-arzt","status":"publish","type":"post","link":"https:\/\/huisartsenpostendelimes.nl\/de\/nieuws\/teil-2-in-der-serie-revisionsprozess-leitender-arzt\/","title":{"rendered":"Teil 2 in der Serienrevision des Directing Physician Prozesses"},"content":{"rendered":"\n<p><em>von Mathilda Boer \u2013 Qualit\u00e4tsbeauftragte<\/em><\/p>\n\n\n\n<p><em>Triage-Kriterien<\/em><\/p>\n\n\n\n<p>Ein wichtiges Dokument, das die Triage-Kriterien erl\u00e4utert, ist das Dringlichkeitscode-Protokoll.&nbsp; Ein entscheidender Teil der Triage und daher zu wichtig, um sie auf einen Link zu beschr\u00e4nken. Wir m\u00f6chten Ihnen erkl\u00e4ren, was wir unter den oben genannten Triage-Kriterien verstehen.<\/p>\n\n\n\n<p>Basierend auf der Triage durch das NTS erstellt ein Triagist\/Arzthelfer einen Dringlichkeitscode. Es gibt eine Reihe allgemeiner Triage-Kriterien, die eine Rolle spielen und die Dringlichkeit erh\u00f6hen (\u21d1) oder verringern (\u21d3) k\u00f6nnen. <\/p>\n\n\n\n<p><strong>Kontextfaktoren <\/strong><strong>\u21d1<\/strong><strong> oder <\/strong><strong>\u21d3<\/strong><strong><\/strong><\/p>\n\n\n\n<p>Faktoren, die die eventuellen Dringlichkeiten beeinflussen, sind:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Dauer der Beschwerde und ihr Verlauf;<\/li>\n\n\n\n<li>Andere Krankheiten und Medikamenteneinnahme;<\/li>\n\n\n\n<li>Kommunikationsprobleme oder unklare Hilfeersuchen;<\/li>\n\n\n\n<li>Keine Pflege.<\/li>\n<\/ul>\n\n\n\n<p><strong>Risikogruppen <\/strong><strong>\u21d1<\/strong><strong><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Alter;<\/li>\n\n\n\n<li>Alter unter drei Monaten;<\/li>\n\n\n\n<li>Schwanger;<\/li>\n\n\n\n<li>Chronisch krank;<\/li>\n\n\n\n<li>Patienten mit einem geschw\u00e4chten Immunsystem (Chemotherapie, AIDS);<\/li>\n\n\n\n<li>K\u00fcrzliche Operation oder Aufnahme;<\/li>\n\n\n\n<li>Inkonsistente Geschichte\/Erz\u00e4hlung passt nicht zusammen.\n<ul class=\"wp-block-list\">\n<li>Ein Beispiel daf\u00fcr ist ein Betreuer, der betont, dass er sich Sorgen um den Patienten macht, w\u00e4hrend er selbst die Beschwerden verharmlost.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<p><strong>Alarme <\/strong><strong>\u21d1<\/strong><strong><\/strong><\/p>\n\n\n\n<p>Was sind rote Fahnen?<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Zweiter Kontakt;<\/li>\n\n\n\n<li>Starke Schmerzen, Angstzust\u00e4nde oder Unruhe (dies gilt auch f\u00fcr die ernsthaft besorgte Umgebung);<\/li>\n\n\n\n<li>Schnelle Verschlechterung des Zustands;<\/li>\n\n\n\n<li>Nicht-Flusen-Feeling des Triagisten.<\/li>\n<\/ul>\n\n\n\n<p>In allen oben genannten Situationen ist es gut, wenn die Triage-Krankenschwester die Dringlichkeit entsprechend anpasst.<\/p>\n\n\n\n<p><em>Das neue Dokument Process Regiearts enth\u00e4lt viele neue Informationen \u2013 sind Sie neugierig geworden? Schauen Sie sich das umgeschriebene Dokument <a href=\"https:\/\/temporary.mindd.dev\/wp-content\/uploads\/2023\/09\/20230526_Proces_regiearts_1.pdf\">HIER an<\/a> &gt;&gt;.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>von Mathilda Boer \u2013 Qualit\u00e4tsbeauftragter Triage-Kriterien Ein wichtiges Dokument, das die Triage-Kriterien erkl\u00e4rt, ist das Dringlichkeitscode-Protokoll.&nbsp; Ein entscheidender Teil der Triage und daher zu wichtig, um sie auf einen Link zu beschr\u00e4nken. Wir m\u00f6chten Ihnen erkl\u00e4ren, was wir unter den oben genannten Triage-Kriterien verstehen. Basierend auf der Triage durch das NTS erstellt ein Triagist\/Arzthelfer einen Dringlichkeitscode. Es gibt eine Reihe allgemeiner Triage-Kriterien, die eine Rolle spielen und die Dringlichkeit erh\u00f6hen (\u21d1) oder verringern (\u21d3) k\u00f6nnen. Kontextfaktoren \u21d1 oder \u21d3 Faktoren, die die eventuellen Dringlichkeiten beeinflussen, sind: Risikogruppen \u21d1 Alarmsignale \u21d1 Was [&#8230;]<\/p>\n","protected":false},"author":3,"featured_media":56504,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"editor_notices":[],"footnotes":""},"categories":[47],"class_list":["post-54293","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-intern-nieuws"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Teil 2 in der Serienrevision des Directing Physician Prozesses - Huisartsenposten De Limes - Deutsch<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/huisartsenpostendelimes.nl\/de\/nieuws\/teil-2-in-der-serie-revisionsprozess-leitender-arzt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Teil 2 in der Serienrevision des Directing Physician Prozesses - Huisartsenposten De Limes - Deutsch\" \/>\n<meta property=\"og:description\" content=\"von Mathilda Boer \u2013 Qualit\u00e4tsbeauftragter Triage-Kriterien Ein wichtiges Dokument, das die Triage-Kriterien erkl\u00e4rt, ist das Dringlichkeitscode-Protokoll.&nbsp; Ein entscheidender Teil der Triage und daher zu wichtig, um sie auf einen Link zu beschr\u00e4nken. Wir m\u00f6chten Ihnen erkl\u00e4ren, was wir unter den oben genannten Triage-Kriterien verstehen. Basierend auf der Triage durch das NTS erstellt ein Triagist\/Arzthelfer einen Dringlichkeitscode. Es gibt eine Reihe allgemeiner Triage-Kriterien, die eine Rolle spielen und die Dringlichkeit erh\u00f6hen (\u21d1) oder verringern (\u21d3) k\u00f6nnen. Kontextfaktoren \u21d1 oder \u21d3 Faktoren, die die eventuellen Dringlichkeiten beeinflussen, sind: Risikogruppen \u21d1 Alarmsignale \u21d1 Was [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/huisartsenpostendelimes.nl\/de\/nieuws\/teil-2-in-der-serie-revisionsprozess-leitender-arzt\/\" \/>\n<meta property=\"og:site_name\" content=\"Huisartsenposten De Limes - Deutsch\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-22T19:46:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-19T14:32:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/huisartsenpostendelimes.nl\/de\/wp-content\/uploads\/sites\/136\/2024\/05\/hap-leiderdorp.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MINDD\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"MINDD\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/huisartsenpostendelimes.nl\/de\/nieuws\/teil-2-in-der-serie-revisionsprozess-leitender-arzt\/\",\"url\":\"https:\/\/huisartsenpostendelimes.nl\/de\/nieuws\/teil-2-in-der-serie-revisionsprozess-leitender-arzt\/\",\"name\":\"Teil 2 in der Serienrevision des Directing Physician Prozesses - Huisartsenposten De Limes - Deutsch\",\"isPartOf\":{\"@id\":\"https:\/\/huisartsenpostendelimes.nl\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/huisartsenpostendelimes.nl\/de\/nieuws\/teil-2-in-der-serie-revisionsprozess-leitender-arzt\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/huisartsenpostendelimes.nl\/de\/nieuws\/teil-2-in-der-serie-revisionsprozess-leitender-arzt\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/huisartsenpostendelimes.nl\/de\/wp-content\/uploads\/sites\/136\/2024\/05\/hap-leiderdorp.jpg\",\"datePublished\":\"2023-08-22T19:46:42+00:00\",\"dateModified\":\"2024-05-19T14:32:25+00:00\",\"author\":{\"@id\":\"https:\/\/huisartsenpostendelimes.nl\/de\/#\/schema\/person\/a9e28e081516b814b3224fb1c8f07206\"},\"breadcrumb\":{\"@id\":\"https:\/\/huisartsenpostendelimes.nl\/de\/nieuws\/teil-2-in-der-serie-revisionsprozess-leitender-arzt\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/huisartsenpostendelimes.nl\/de\/nieuws\/teil-2-in-der-serie-revisionsprozess-leitender-arzt\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/huisartsenpostendelimes.nl\/de\/nieuws\/teil-2-in-der-serie-revisionsprozess-leitender-arzt\/#primaryimage\",\"url\":\"https:\/\/huisartsenpostendelimes.nl\/de\/wp-content\/uploads\/sites\/136\/2024\/05\/hap-leiderdorp.jpg\",\"contentUrl\":\"https:\/\/huisartsenpostendelimes.nl\/de\/wp-content\/uploads\/sites\/136\/2024\/05\/hap-leiderdorp.jpg\",\"width\":1280,\"height\":720,\"caption\":\"Standort Leiderdorp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/huisartsenpostendelimes.nl\/de\/nieuws\/teil-2-in-der-serie-revisionsprozess-leitender-arzt\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/huisartsenpostendelimes.nl\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Teil 2 in der Serienrevision des Directing Physician Prozesses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/huisartsenpostendelimes.nl\/de\/#website\",\"url\":\"https:\/\/huisartsenpostendelimes.nl\/de\/\",\"name\":\"Huisartsenposten De Limes - Deutsch\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/huisartsenpostendelimes.nl\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/huisartsenpostendelimes.nl\/de\/#\/schema\/person\/a9e28e081516b814b3224fb1c8f07206\",\"name\":\"MINDD\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/huisartsenpostendelimes.nl\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/huisartsenpostendelimes.nl\/de\/wp-content\/litespeed\/avatar\/136\/cb20a4a779c84cdbe340e6ad267e9e9a.jpg?ver=1778617969\",\"contentUrl\":\"https:\/\/huisartsenpostendelimes.nl\/de\/wp-content\/litespeed\/avatar\/136\/cb20a4a779c84cdbe340e6ad267e9e9a.jpg?ver=1778617969\",\"caption\":\"MINDD\"},\"url\":\"https:\/\/huisartsenpostendelimes.nl\/de\/nieuws\/author\/mindd-beheer\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Teil 2 in der Serienrevision des Directing Physician Prozesses - Huisartsenposten De Limes - Deutsch","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/huisartsenpostendelimes.nl\/de\/nieuws\/teil-2-in-der-serie-revisionsprozess-leitender-arzt\/","og_locale":"de_DE","og_type":"article","og_title":"Teil 2 in der Serienrevision des Directing Physician Prozesses - Huisartsenposten De Limes - Deutsch","og_description":"von Mathilda Boer \u2013 Qualit\u00e4tsbeauftragter Triage-Kriterien Ein wichtiges Dokument, das die Triage-Kriterien erkl\u00e4rt, ist das Dringlichkeitscode-Protokoll.&nbsp; Ein entscheidender Teil der Triage und daher zu wichtig, um sie auf einen Link zu beschr\u00e4nken. Wir m\u00f6chten Ihnen erkl\u00e4ren, was wir unter den oben genannten Triage-Kriterien verstehen. Basierend auf der Triage durch das NTS erstellt ein Triagist\/Arzthelfer einen Dringlichkeitscode. Es gibt eine Reihe allgemeiner Triage-Kriterien, die eine Rolle spielen und die Dringlichkeit erh\u00f6hen (\u21d1) oder verringern (\u21d3) k\u00f6nnen. Kontextfaktoren \u21d1 oder \u21d3 Faktoren, die die eventuellen Dringlichkeiten beeinflussen, sind: Risikogruppen \u21d1 Alarmsignale \u21d1 Was [...]","og_url":"https:\/\/huisartsenpostendelimes.nl\/de\/nieuws\/teil-2-in-der-serie-revisionsprozess-leitender-arzt\/","og_site_name":"Huisartsenposten De Limes - Deutsch","article_published_time":"2023-08-22T19:46:42+00:00","article_modified_time":"2024-05-19T14:32:25+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/huisartsenpostendelimes.nl\/de\/wp-content\/uploads\/sites\/136\/2024\/05\/hap-leiderdorp.jpg","type":"image\/jpeg"}],"author":"MINDD","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"MINDD","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/huisartsenpostendelimes.nl\/de\/nieuws\/teil-2-in-der-serie-revisionsprozess-leitender-arzt\/","url":"https:\/\/huisartsenpostendelimes.nl\/de\/nieuws\/teil-2-in-der-serie-revisionsprozess-leitender-arzt\/","name":"Teil 2 in der Serienrevision des Directing Physician Prozesses - Huisartsenposten De Limes - Deutsch","isPartOf":{"@id":"https:\/\/huisartsenpostendelimes.nl\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/huisartsenpostendelimes.nl\/de\/nieuws\/teil-2-in-der-serie-revisionsprozess-leitender-arzt\/#primaryimage"},"image":{"@id":"https:\/\/huisartsenpostendelimes.nl\/de\/nieuws\/teil-2-in-der-serie-revisionsprozess-leitender-arzt\/#primaryimage"},"thumbnailUrl":"https:\/\/huisartsenpostendelimes.nl\/de\/wp-content\/uploads\/sites\/136\/2024\/05\/hap-leiderdorp.jpg","datePublished":"2023-08-22T19:46:42+00:00","dateModified":"2024-05-19T14:32:25+00:00","author":{"@id":"https:\/\/huisartsenpostendelimes.nl\/de\/#\/schema\/person\/a9e28e081516b814b3224fb1c8f07206"},"breadcrumb":{"@id":"https:\/\/huisartsenpostendelimes.nl\/de\/nieuws\/teil-2-in-der-serie-revisionsprozess-leitender-arzt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/huisartsenpostendelimes.nl\/de\/nieuws\/teil-2-in-der-serie-revisionsprozess-leitender-arzt\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/huisartsenpostendelimes.nl\/de\/nieuws\/teil-2-in-der-serie-revisionsprozess-leitender-arzt\/#primaryimage","url":"https:\/\/huisartsenpostendelimes.nl\/de\/wp-content\/uploads\/sites\/136\/2024\/05\/hap-leiderdorp.jpg","contentUrl":"https:\/\/huisartsenpostendelimes.nl\/de\/wp-content\/uploads\/sites\/136\/2024\/05\/hap-leiderdorp.jpg","width":1280,"height":720,"caption":"Standort Leiderdorp"},{"@type":"BreadcrumbList","@id":"https:\/\/huisartsenpostendelimes.nl\/de\/nieuws\/teil-2-in-der-serie-revisionsprozess-leitender-arzt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/huisartsenpostendelimes.nl\/de\/"},{"@type":"ListItem","position":2,"name":"Teil 2 in der Serienrevision des Directing Physician Prozesses"}]},{"@type":"WebSite","@id":"https:\/\/huisartsenpostendelimes.nl\/de\/#website","url":"https:\/\/huisartsenpostendelimes.nl\/de\/","name":"Huisartsenposten De Limes - Deutsch","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/huisartsenpostendelimes.nl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/huisartsenpostendelimes.nl\/de\/#\/schema\/person\/a9e28e081516b814b3224fb1c8f07206","name":"MINDD","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/huisartsenpostendelimes.nl\/de\/#\/schema\/person\/image\/","url":"https:\/\/huisartsenpostendelimes.nl\/de\/wp-content\/litespeed\/avatar\/136\/cb20a4a779c84cdbe340e6ad267e9e9a.jpg?ver=1778617969","contentUrl":"https:\/\/huisartsenpostendelimes.nl\/de\/wp-content\/litespeed\/avatar\/136\/cb20a4a779c84cdbe340e6ad267e9e9a.jpg?ver=1778617969","caption":"MINDD"},"url":"https:\/\/huisartsenpostendelimes.nl\/de\/nieuws\/author\/mindd-beheer\/"}]}},"_links":{"self":[{"href":"https:\/\/huisartsenpostendelimes.nl\/de\/wp-json\/wp\/v2\/posts\/54293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/huisartsenpostendelimes.nl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/huisartsenpostendelimes.nl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/huisartsenpostendelimes.nl\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/huisartsenpostendelimes.nl\/de\/wp-json\/wp\/v2\/comments?post=54293"}],"version-history":[{"count":1,"href":"https:\/\/huisartsenpostendelimes.nl\/de\/wp-json\/wp\/v2\/posts\/54293\/revisions"}],"predecessor-version":[{"id":56503,"href":"https:\/\/huisartsenpostendelimes.nl\/de\/wp-json\/wp\/v2\/posts\/54293\/revisions\/56503"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/huisartsenpostendelimes.nl\/de\/wp-json\/wp\/v2\/media\/56504"}],"wp:attachment":[{"href":"https:\/\/huisartsenpostendelimes.nl\/de\/wp-json\/wp\/v2\/media?parent=54293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/huisartsenpostendelimes.nl\/de\/wp-json\/wp\/v2\/categories?post=54293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}